{"id":99,"count":3,"description":"","link":"https:\/\/www.medicare-asia.com\/id\/category\/mental-health\/","name":"Mental Health","slug":"mental-health","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medicare-asia.com\/id\/wp-json\/wp\/v2\/categories\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medicare-asia.com\/id\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.medicare-asia.com\/id\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.medicare-asia.com\/id\/wp-json\/wp\/v2\/posts?categories=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}